{"id":95802,"date":"2025-08-29T06:12:58","date_gmt":"2025-08-29T12:12:58","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=95802"},"modified":"2025-08-29T06:12:58","modified_gmt":"2025-08-29T12:12:58","slug":"corte-constitucional-de-tailandia-destituye-a-primera-ministra","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/corte-constitucional-de-tailandia-destituye-a-primera-ministra\/","title":{"rendered":"Corte Constitucional de Tailandia destituye a primera ministra"},"content":{"rendered":"\n<p>AFP<\/p>\n\n\n\n<p>La Corte Constitucional tailandesa destituy\u00f3 el viernes a la primera ministra Paetongtarn Shinawatra y a su gabinete por la gesti\u00f3n de una disputa diplom\u00e1tica con Camboya.<\/p>\n\n\n\n<p>En su veredicto, los nueve jueces del tribunal consideraron que la dirigente no hab\u00eda respetado las normas \u00e9ticas gubernamentales durante una llamada telef\u00f3nica con el exgobernante camboyano Hun Sen en junio, en medio de tensiones con el pa\u00eds vecino.<\/p>\n\n\n\n<p>Shinawatra se convierte en el tercer miembro de su familia en abandonar la jefatura de gobierno, despu\u00e9s de su padre Thaksin y su t\u00eda Yingluck, ambos derrocados por golpes de Estado militares.<\/p>\n\n\n\n<p>La Corte Constitucional hab\u00eda destituido hace un a\u00f1o a su predecesor, Srettha Thavisin.<\/p>\n\n\n\n<p>La l\u00edder, de 39 a\u00f1os, afirm\u00f3 que hab\u00eda hecho todo lo posible por actuar en inter\u00e9s nacional.<\/p>\n\n\n\n<p>&#8220;Mis intenciones eran beneficiar al pa\u00eds, no obtener ganancias personales, sino mejorar la vida de la gente, incluidos civiles y soldados&#8221;, declar\u00f3 a la prensa tras conocer la sentencia.<\/p>\n\n\n\n<p>Sin un candidato claro para asumir el cargo de primer ministro, el reino asi\u00e1tico se enfrenta a un periodo de profunda incertidumbre pol\u00edtica.<\/p>\n\n\n\n<p>Shinawatra fue culpada de haber infringido las normas \u00e9ticas exigidas a un jefe de gobierno durante un llamado con el exdirigente camboyano Hun Sen, que se filtr\u00f3 en internet.<\/p>\n\n\n\n<p>La discusi\u00f3n tuvo lugar en junio durante una escalada entre ambos pa\u00edses, iniciada tras la muerte de un soldado camboyano a finales de mayo en enfrentamientos transfronterizos con el ej\u00e9rcito tailand\u00e9s en una zona en disputa.<\/p>\n\n\n\n<p>En esa conversaci\u00f3n, que fue grabada y difundida sin su consentimiento, llam\u00f3 &#8220;t\u00edo&#8221; a Hun Sen y se refiri\u00f3 a un comandante militar tailand\u00e9s como su &#8220;opositor&#8221;.<\/p>\n\n\n\n<p>El asunto provoc\u00f3 una crisis pol\u00edtica en el pa\u00eds, que llev\u00f3 a los conservadores del Bhumjaithai a abandonar la coalici\u00f3n de gobierno, adem\u00e1s de elevar las tensiones en la frontera con Camboya.<\/p>\n\n\n\n<p>Ambos pa\u00edses fueron protagonistas en julio de cinco d\u00edas de enfrentamientos armados, que causaron 40 muertos y m\u00e1s de 300.000 desplazados.<\/p>\n\n\n\n<p>Desde hace dos d\u00e9cadas, la pol\u00edtica en el pa\u00eds asi\u00e1tico ha estado dominada por una disputa entre la \u00e9lite conservadora promilitar y mon\u00e1rquica, y el clan Shinawatra, al que consideran una amenaza al orden social tradicional tailand\u00e9s.<\/p>\n\n\n\n<p>Hace una semana, el padre de Paetongtarn, Thaksin, fue absuelto en su juicio por delito de lesa majestad. El multimillonario y ex primer ministro de 76 a\u00f1os se enfrentaba a una pena de hasta 15 a\u00f1os de prisi\u00f3n por estos hechos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP La Corte Constitucional tailandesa destituy\u00f3 el viernes a la primera ministra Paetongtarn Shinawatra y a su gabinete por la gesti\u00f3n de una disputa diplom\u00e1tica&hellip; <\/p>\n","protected":false},"author":12,"featured_media":95803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[150,8755,648],"class_list":["post-95802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-noticias","tag-internacionales","tag-paetongtarn-shinawatra","tag-tailandia"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=95802"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95802\/revisions"}],"predecessor-version":[{"id":95804,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95802\/revisions\/95804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media\/95803"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=95802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=95802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=95802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}