{"id":95796,"date":"2025-08-28T12:14:13","date_gmt":"2025-08-28T18:14:13","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=95796"},"modified":"2025-08-28T12:14:13","modified_gmt":"2025-08-28T18:14:13","slug":"condenan-a-dos-pandilleros-de-la-ms-a-30-anos-de-prision-por-el-delito-de-extorsion","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/condenan-a-dos-pandilleros-de-la-ms-a-30-anos-de-prision-por-el-delito-de-extorsion\/","title":{"rendered":"Condenan a dos pandilleros de la MS a 30 a\u00f1os de prisi\u00f3n por el delito de extorsi\u00f3n"},"content":{"rendered":"\n<p>William Santos<\/p>\n\n\n\n<p>Obligaron a su v\u00edctima a entregar dinero mes a mes bajo amenazas.<\/p>\n\n\n\n<p>Dos integrantes de la estructura criminal MS-13 fueron condenadas a 30 a\u00f1os de prisi\u00f3n por el delito de extorsi\u00f3n agravada continuada, tras un proceso judicial que revel\u00f3 c\u00f3mo presionaban a su v\u00edctima para entregas mensuales de dinero mediante amenazas e intimidaci\u00f3n.<\/p>\n\n\n\n<p>Los hechos ocurrieron en abril de 2022, en el distrito de San Pedro Masahuat, en La Paz Oeste. Seg\u00fan la investigaci\u00f3n, Sharon Maderick Escobar Cer\u00f3n y Laura Liseth Flores Hern\u00e1ndez interceptaron a la v\u00edctima mientras se desplazaba en un veh\u00edculo. La forzaron a subir al autom\u00f3vil y, bajo amenazas, comenzaron a exigirle pagos peri\u00f3dicos.<\/p>\n\n\n\n<p>Durante el juicio, el Ministerio P\u00fablico present\u00f3 pruebas contundentes que confirmaron la participaci\u00f3n activa de ambas en el delito, lo que permiti\u00f3 al Tribunal de Sentencia de Zacatecoluca emitir un fallo condenatorio.<\/p>\n\n\n\n<p>Adem\u00e1s de la pena de prisi\u00f3n, las extorsionistas deber\u00e1n pagar $2,500 en concepto de responsabilidad civil, como compensaci\u00f3n a la v\u00edctima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>William Santos Obligaron a su v\u00edctima a entregar dinero mes a mes bajo amenazas. Dos integrantes de la estructura criminal MS-13 fueron condenadas a 30&hellip; <\/p>\n","protected":false},"author":12,"featured_media":95797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[7508,7857],"class_list":["post-95796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-noticias","tag-extorsion","tag-ms13"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=95796"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95796\/revisions"}],"predecessor-version":[{"id":95798,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/95796\/revisions\/95798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media\/95797"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=95796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=95796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=95796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}