{"id":90432,"date":"2024-11-26T06:26:16","date_gmt":"2024-11-26T12:26:16","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=90432"},"modified":"2024-11-26T06:26:18","modified_gmt":"2024-11-26T12:26:18","slug":"cinco-muertos-y-una-sobreviviente-en-accidente-de-avioneta-en-costa-rica","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/cinco-muertos-y-una-sobreviviente-en-accidente-de-avioneta-en-costa-rica\/","title":{"rendered":"Cinco muertos y una sobreviviente en accidente de avioneta en Costa Rica"},"content":{"rendered":"\n<p>AFP<\/p>\n\n\n\n<p>Una avioneta privada con seis personas a bordo se estrell\u00f3 este lunes en los cerros que rodean la ciudad capital de San Jos\u00e9 dejando cinco fallecidos y una sobreviviente en estado cr\u00edtico, inform\u00f3 la Cruz Roja Costarricense.<\/p>\n\n\n\n<p>Los equipos de emergencia llegaron al lugar del siniestro tras varias horas intentando acceder a las escarpadas laderas boscosas donde se estrell\u00f3 la avioneta, un modelo Cessna 206, que viajaba desde Tortuguero, en la&nbsp;<strong>costa<\/strong>&nbsp;norte del Caribe, hacia la capital.<\/p>\n\n\n\n<p>En la aeronave viajaban el piloto, el copiloto y cuatro pasajeros que formaban parte de una empresa de turismo local, informaron medios locales.<\/p>\n\n\n\n<p>La avioneta ten\u00eda como destino el aeropuerto local Tob\u00edas Bola\u00f1os, en el este de la capital costarricense.<\/p>\n\n\n\n<p>Sin embargo, antes de su llegada el piloto pidi\u00f3 dirigirse al cercano aeropuerto internacional Juan Santamar\u00eda por las malas condiciones meteorol\u00f3gicas, momento en que se perdi\u00f3 la se\u00f1al de la aeronave.&nbsp;<\/p>\n\n\n\n<p>Las autoridades todav\u00eda no han realizado un reporte oficial de las causas del siniestro.<\/p>\n\n\n\n<p>Otra avioneta que report\u00f3 el accidente mientras sobrevolaba la zona indic\u00f3 la existencia de bancos de niebla en la zona, conocida como Pico Blanco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP Una avioneta privada con seis personas a bordo se estrell\u00f3 este lunes en los cerros que rodean la ciudad capital de San Jos\u00e9 dejando&hellip; <\/p>\n","protected":false},"author":12,"featured_media":90433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[8230,2638,1043],"class_list":["post-90432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-noticias","tag-accidente-aereo-2","tag-avioneta","tag-costa-rica"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/90432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=90432"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/90432\/revisions"}],"predecessor-version":[{"id":90434,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/90432\/revisions\/90434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media\/90433"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=90432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=90432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=90432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}