{"id":88884,"date":"2024-10-07T10:34:00","date_gmt":"2024-10-07T16:34:00","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=88884"},"modified":"2024-10-07T12:16:30","modified_gmt":"2024-10-07T18:16:30","slug":"huracan-milton-crece-a-categoria-4-amenaza-a-mexico-y-florida","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/huracan-milton-crece-a-categoria-4-amenaza-a-mexico-y-florida\/","title":{"rendered":"Milton se torna hurac\u00e1n de categor\u00eda m\u00e1xima y amenaza a M\u00e9xico y Florida"},"content":{"rendered":"\n<p>AFP<\/p>\n\n\n\n<p>El hurac\u00e1n&nbsp;<strong>Milton<\/strong>&nbsp;cobr\u00f3 fuerza el lunes y se convirti\u00f3 en una tormenta potencialmente catastr\u00f3fica de categor\u00eda 5, la m\u00e1xima en la escala, que avanza rumbo a la costa oeste de Florida, inform\u00f3 el centro estadounidense de huracanes (NHC).&nbsp;<\/p>\n\n\n\n<p>Segundo gran hurac\u00e1n registrado en el golfo de M\u00e9xico en dos semanas, Milton se fortaleci\u00f3 r\u00e1pidamente y escal\u00f3 en poco tiempo a la categor\u00eda 4, un hurac\u00e1n &#8220;extremadamente peligroso&#8221; seg\u00fan el NHC, cuya escala de referencia va de 1 a 5.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hurac\u00e1n Milton crece a categor\u00eda 4, amenaza a M\u00e9xico y Florida | AFP\" width=\"790\" height=\"444\" src=\"https:\/\/www.youtube.com\/embed\/2Fi-VVzrp7A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Antes de golpear el mi\u00e9rcoles el oeste de Florida, Estados Unidos, las autoridades esperan que provoque fuertes vientos y un aumento del nivel de agua de hasta 1,5 metros en la pen\u00ednsula mexicana de Yucat\u00e1n, con &#8220;olas grandes y destructivas&#8221;.<\/p>\n\n\n\n<p>Hace apenas 10 d\u00edas, el hurac\u00e1n Helene provoc\u00f3 m\u00e1s de 220 muertos en el sur de Estados Unidos.&nbsp;<\/p>\n\n\n\n<p>Las autoridades de Florida ordenaron este lunes nuevas evacuaciones en la misma regi\u00f3n que todav\u00eda se recupera de esos da\u00f1os.<\/p>\n\n\n\n<p>Milton podr\u00eda traer a Florida lluvias de hasta 25 cm (con focos puntuales de hasta 38 cm) que causar\u00edan estragos con inundaciones repentinas en \u00e1reas urbanas, seg\u00fan el NHC.&nbsp;<\/p>\n\n\n\n<p>El organismo advirti\u00f3 que los huracanes m\u00e1s potentes, de categor\u00eda 3 en adelante, generan &#8220;da\u00f1os devastadores&#8221; incluso para casas de construcci\u00f3n firme, y que &#8220;faltar\u00e1 electricidad y agua por varios d\u00edas tras el paso de la tormenta&#8221;.&nbsp;<\/p>\n\n\n\n<p>La alcaldesa de Tampa, Jane Castor, dijo a la CNN que todav\u00eda estaban limpiando la ciudad tras el paso de Helene y que la lluvia de la nueva tormenta ser\u00eda &#8220;bastante dif\u00edcil, sin mencionar la marejada cicl\u00f3nica y los da\u00f1os causados por el viento&#8221;.&nbsp;<\/p>\n\n\n\n<p>El gobernador de Florida, Ron DeSantis, ha declarado 51 de los 67 condados del estado en situaci\u00f3n de emergencia, y advirti\u00f3 que Milton podr\u00eda tener &#8220;impactos importantes, muy importantes&#8221;.&nbsp;<\/p>\n\n\n\n<p>El presidente dijo en un comunicado que su gobierno estaba preparando &#8220;recursos para salvar vidas&#8221;.&nbsp;<\/p>\n\n\n\n<p>Los cient\u00edficos sostienen que el cambio clim\u00e1tico probablemente juega un papel en la r\u00e1pida intensificaci\u00f3n de los huracanes, porque superficies oce\u00e1nicas m\u00e1s c\u00e1lidas liberan m\u00e1s vapor de agua, lo que les proporciona a las tormentas m\u00e1s energ\u00eda y en consecuencia intensifica sus vientos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Bombardeo de desinformaci\u00f3n &#8211;<\/h2>\n\n\n\n<p>Helene irrumpi\u00f3 en la costa de Florida como hurac\u00e1n de categor\u00eda 4 el 26 de septiembre y dej\u00f3 un tendal de destrucci\u00f3n tierra adentro hasta las monta\u00f1as de los Apalaches, con lluvias torrenciales e inundaciones.&nbsp;&nbsp;<\/p>\n\n\n\n<p>La tormenta caus\u00f3 m\u00e1s de 220 muertes, lo que la convierte en el desastre natural m\u00e1s mort\u00edfero que ha azotado al pa\u00eds desde el hurac\u00e1n Katrina en 2005. Y la cifra de fallecidos sigue aumentando. &nbsp;<\/p>\n\n\n\n<p>Los socorristas contin\u00faan trabajando para encontrar supervivientes y llevar electricidad y agua potable a las comunidades monta\u00f1osas aisladas por la tormenta.&nbsp;<\/p>\n\n\n\n<p>La magnitud del desastre no ha evitado que haya sido el centro de una campa\u00f1a de desinformaci\u00f3n. El candidato presidencial republicano, Donald Trump, acus\u00f3 a su rival dem\u00f3crata para la Casa Blanca, la vicepresidenta Kamala Harris, de destinar a los migrantes parte del presupuesto destinado a ayudar a los afectados por Helene.<\/p>\n\n\n\n<p>&#8220;Es rid\u00edculo y simplemente falso&#8221;, respondi\u00f3 el domingo la directora de la agencia federal de respuesta a desastres naturales (FEMA).<\/p>\n\n\n\n<p>FEMA y verificadores externos de contenido han se\u00f1alado que su programa para brindar refugio y ayuda a los migrantes est\u00e1 financiado directamente por el Congreso, completamente separado del presupuesto que recibe para atender desastres naturales.&nbsp;<\/p>\n\n\n\n<p>La cadena ABC inform\u00f3 que ante esta campa\u00f1a agentes de seguridad est\u00e1n monitoreando amenazas a funcionarios de FEMA y otras agencias federales.<\/p>\n\n\n\n<p>Un usuario sugiri\u00f3 &#8220;que una milicia vaya contra FEMA&#8221; en una publicaci\u00f3n en la red social X que tuvo m\u00e1s de medio mill\u00f3n de visitas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP El hurac\u00e1n&nbsp;Milton&nbsp;cobr\u00f3 fuerza el lunes y se convirti\u00f3 en una tormenta potencialmente catastr\u00f3fica de categor\u00eda 5, la m\u00e1xima en la escala, que avanza rumbo&hellip; <\/p>\n","protected":false},"author":12,"featured_media":88885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[432,8070,150],"class_list":["post-88884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-noticias","tag-clima","tag-huracan-milton","tag-internacionales"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/88884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=88884"}],"version-history":[{"count":3,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/88884\/revisions"}],"predecessor-version":[{"id":88890,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/88884\/revisions\/88890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media\/88885"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=88884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=88884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=88884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}