{"id":83042,"date":"2024-02-22T16:05:22","date_gmt":"2024-02-22T22:05:22","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=83042"},"modified":"2024-02-22T16:05:22","modified_gmt":"2024-02-22T22:05:22","slug":"menores-detenidos-por-vinculos-con-pandillas-seran-procesados-y-enviados-a-la-carcel","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/menores-detenidos-por-vinculos-con-pandillas-seran-procesados-y-enviados-a-la-carcel\/","title":{"rendered":"Menores detenidos por v\u00ednculos con pandillas ser\u00e1n procesados y enviados a la c\u00e1rcel"},"content":{"rendered":"\n<p>Alex Jim\u00e9nez<\/p>\n\n\n\n<p>El pasado martes, las autoridades llevaron a cabo la detenci\u00f3n de ocho menores de entre 12 y 15 a\u00f1os de edad en Chalatenango, por presunta participaci\u00f3n en actividades relacionadas con la Mara Salvatrucha 13 (MS13). En una conferencia de prensa realizada este d\u00eda, funcionarios del Gobierno brindaron detalles sobre este operativo.<\/p>\n\n\n\n<p>&#8220;Los menores detenidos por v\u00ednculos con pandillas ser\u00e1n procesados por pertenencia a organizaciones il\u00edcitas e ir\u00e1n a la c\u00e1rcel&#8221;, advirti\u00f3 el Ministro de Justicia, Gustavo Villatoro. &#8220;Sepan que ahora un menor de edad entre los 12 y 18 a\u00f1os va a responder con penas de prisi\u00f3n de hasta 20 a\u00f1os, que casualmente es la pena m\u00ednima para los delitos de agrupaciones il\u00edcitas&#8221;, agreg\u00f3.<\/p>\n\n\n\n<p>El Ministro Villatoro destac\u00f3 que en los \u00faltimos a\u00f1os m\u00e1s de 7,900 menores de edad fueron reclutados por las pandillas, pero enfatiz\u00f3 que los responsables de estos actos criminales van a enfrentar las consecuencias de sus acciones ante la justicia.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Menores detenidos por v\u00ednculos con pandillas ser\u00e1n procesados por pertenencia a organizaciones il\u00edcitas e ir\u00e1n a la c\u00e1rcel&quot;, advierte el Ministro de Justicia, Gustavo Villatoro.  <a href=\"https:\/\/twitter.com\/hashtag\/TNM?src=hash&amp;ref_src=twsrc%5Etfw\">#TNM<\/a> <a href=\"https:\/\/t.co\/7W9LlwmfOr\">pic.twitter.com\/7W9LlwmfOr<\/a><\/p>&mdash; Telenoticias Megavisi\u00f3n (@TelenoticiasGMV) <a href=\"https:\/\/twitter.com\/TelenoticiasGMV\/status\/1760755357574369647?ref_src=twsrc%5Etfw\">February 22, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Por su parte, el Ministro de la Defensa, Ren\u00e9 Merino Monroy, afirm\u00f3 que gracias a las denuncias ciudadanas se ha logrado identificar a menores de edad con v\u00ednculos con pandillas, lo que ha permitido desarticular sus estructuras y prevenir futuros actos delictivos.<\/p>\n\n\n\n<p>El Director de la Polic\u00eda Nacional Civil (PNC), Mauricio Arriaza Chicas, asegur\u00f3 que est\u00e1n intensificando la vigilancia en los centros educativos del pa\u00eds para evitar que m\u00e1s j\u00f3venes sean reclutados por las pandillas. &#8220;Como Polic\u00eda Nacional Civil, informamos a la poblaci\u00f3n salvadore\u00f1a que estos menores de edad ubicados en Chalatenango, conforme a las reformas a la Ley Penal Juvenil, han sido puestos a la orden de la Fiscal\u00eda General de la Rep\u00fablica&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p>&#8220;El llamado es para los padres de familia y todos los salvadore\u00f1os, estar atentos de las actitudes y aptitudes de nuestros hijos, verificando las redes sociales de ellos&#8221;, concluy\u00f3 el director de la PNC, instando a la comunidad a colaborar en la prevenci\u00f3n del reclutamiento de menores por parte de pandillas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado martes, las autoridades llevaron a cabo la detenci\u00f3n de ocho menores de entre 12 y 15 a\u00f1os de edad en Chalatenango, por presunta participaci\u00f3n en actividades relacionadas con la Mara Salvatrucha 13 (MS13). En una conferencia de prensa realizada este d\u00eda, funcionarios del Gobierno brindaron detalles sobre este operativo.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-83042","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/83042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=83042"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/83042\/revisions"}],"predecessor-version":[{"id":83044,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/83042\/revisions\/83044"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=83042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=83042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=83042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}