{"id":82355,"date":"2024-02-05T11:56:33","date_gmt":"2024-02-05T17:56:33","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=82355"},"modified":"2024-02-05T11:56:33","modified_gmt":"2024-02-05T17:56:33","slug":"aumenta-a-122-los-muertos-por-los-incendios-forestales-en-chile","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/aumenta-a-122-los-muertos-por-los-incendios-forestales-en-chile\/","title":{"rendered":"Aumenta a 122 los muertos por los incendios forestales en Chile"},"content":{"rendered":"\n<p>por Javier TORRES con Paula BUSTAMANTE en Santiago<\/p>\n\n\n\n<p>&#8220;Chile entero llora a Valpara\u00edso&#8221;, dijo el presidente Gabriel Boric, al decretar desde este lunes dos d\u00edas de duelo por los 122 muertos y miles de personas sin casa que han dejado hasta ahora los incendios forestales que ya figuran entre los tres m\u00e1s mort\u00edferos del mundo del siglo XXI.<\/p>\n\n\n\n<p>Sin luz, poca agua y mucho calor, vecinos de Quilpu\u00e9 y Villa Independencia, en los cerros poblados de la regi\u00f3n de Valpara\u00edso, unos 120 km al noroeste de Santiago, padecen la falta de servicios b\u00e1sicos para poder reponerse entre calles tapadas de escombros, autos carbonizados y cenizas.<\/p>\n\n\n\n<p>&#8220;Se salv\u00f3 lo m\u00e1s importante de mi casa, pero ahora estamos sin luz, no podemos hacer nada ni cargar los celulares. El tr\u00e1fico est\u00e1 complicado con autos quemados, est\u00e1 todo devastado&#8221;, cont\u00f3 a la AFP, Patricia Guzm\u00e1n, de 63 a\u00f1os desde el sector Canal Chacao de Quilp\u00fae, arrasado por los llamas, donde la cuadra donde vive qued\u00f3 en pie.<\/p>\n\n\n\n<p>La movilizaci\u00f3n en las rutas de las zonas afectadas empeora a medida que llegan voluntarios, gente que quiere ayudar a familias, asistir a mascotas, y entregar alimentos, agua, carpas. Tambi\u00e9n est\u00e1n trabajando bomberos y equipos oficiales buscando v\u00edctimas en sitios quemados.<\/p>\n\n\n\n<p>En pleno verano austral, esta zona de playas visitadas por turistas tiene gran parte de sus hoteles sin empleados porque han resultado afectados por la cat\u00e1strofe, que ha dejado una estela de colinas con casas quemadas y v\u00edas estrechas tapadas de veh\u00edculos que hasta ahora se desconoce si estaban estacionados o si estaban ocupados por personas que intentaron evacuar.&nbsp;<\/p>\n\n\n\n<p>El \u00faltimo balance &nbsp;de este lunes elev\u00f3 a 122 los muertos, de los cuales solo 32 han podido ser identificados, inform\u00f3 un comunicado del Servicio M\u00e9dico Legal (SML), \u00f3rgano estatal designado por la presidencia para dar el n\u00famero oficial de v\u00edctimas fatales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Buscando v\u00edctimas &#8211;<\/h2>\n\n\n\n<p>A\u00fan sin cifras de personas que perdieron casas, ya son casi 15.000 las viviendas da\u00f1adas, inform\u00f3 el subsecretario del ministerio del Interior, Manuel Monsalve, quien agreg\u00f3 que la mayor cantidad de damnificados se concentra en Vi\u00f1a del Mar.<\/p>\n\n\n\n<p>&#8220;Hay 190 desaparecidos en Vi\u00f1a del Mar&#8221;, dijo la alcaldesa de esta ciudad, Macarena Ripamonti, quien agreg\u00f3 que hay &#8220;20.000 vecinos pertenecientes a siete barrios de la comuna (de Vi\u00f1a) que han resultado damnificados&#8221;.&nbsp;<\/p>\n\n\n\n<p>Algunos focos de los incendios empezaron el mi\u00e9rcoles, el mismo d\u00eda que se hizo sentir una ola de calor con temperaturas por encima de 40 grados Celsius, y el viernes en la tarde se propagaron en cuesti\u00f3n de horas.&nbsp;<\/p>\n\n\n\n<p>Los brutales incendios figuran entre los tres m\u00e1s mort\u00edferos del siglo XXI, despu\u00e9s de los de Australia en 2009 (179 fallecidos) y los de Haw\u00e1i en agosto 2023 (m\u00e1s de 100 muertos).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Fuegos activos &#8211;<\/h2>\n\n\n\n<p>Las condiciones clim\u00e1ticas mejoraron con un fen\u00f3meno t\u00edpico en la costa del Pac\u00edfico que produce mucha nubosidad, alta humedad y disminuye el calor, lo que &#8220;ayuda a enfriar el incendio&#8221; aunque &#8220;habr\u00e1 altas temperaturas hasta el martes&#8221;, dijo la ministra del Interior, Carolina Toh\u00e1.<\/p>\n\n\n\n<p>Sin embargo, los equipos a\u00fan combaten 40 incendios, con algunos focos que causaron evacuaciones preventivas el domingo en Til Til, 60 km al norte de Santiago, y en Galvarino, 400 km al sur de la capital, cerca de una extensa regi\u00f3n afectadas tambi\u00e9n por fuegos de gran magnitud en febrero del a\u00f1o pasado.&nbsp;<\/p>\n\n\n\n<p>Las partes m\u00e1s castigadas se encuentran en una zona que desde hace d\u00e9cadas se ha superpoblado sin planificaci\u00f3n urban\u00edstica y en la que, por su cercan\u00eda a la costa del Pac\u00edfico y tambi\u00e9n a Santiago, viven familias de clase media y otras en asentamientos precarios y pobres.<\/p>\n\n\n\n<p>La alta densidad poblacional en terrenos de dif\u00edcil acceso, sumada a la prolongada sequ\u00eda en Chile y las altas temperaturas, propiciaron estos siniestros.<\/p>\n\n\n\n<p>Tanto Boric como el Ministerio el Interior ya han declarado que sospechan que los incendios fueron provocados.&nbsp;<\/p>\n\n\n\n<p>En Villa Independencia, que concentra el mayor n\u00famero de muertos y da\u00f1os, Daniela Barraza, estudiante de Educaci\u00f3n de 36 a\u00f1os, junto a su hijo con autismo, est\u00e1 recibiendo por ahora ayuda de vecinos. &#8220;Quedamos con lo puesto, mi hijo sin zapatos, mi hija sin ropa, quedamos as\u00ed, de brazos cruzados&#8221;, dijo a la AFP.<\/p>\n\n\n\n<p>El papa Francisco pidi\u00f3 oraciones a sus fieles por las v\u00edctimas. Francia, Espa\u00f1a y el alto representante para Asuntos Exteriores de la Uni\u00f3n Europea (UE), Josep Borrell, ofrecieron ayuda por esta cat\u00e1strofe en Chile que recuerda &#8220;los estragos de la sequ\u00eda y el clima&#8221;, dijo.<\/p>\n\n\n\n<p>Una ola de calor con m\u00e1ximos de temperatura agobia estos d\u00edas al Cono Sur americano, donde el fen\u00f3meno clim\u00e1tico natural de El Ni\u00f1o se agudiza por el calentamiento global provocado por la actividad humana, seg\u00fan especialistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Chile entero llora a Valpara\u00edso&#8221;, dijo el presidente Gabriel Boric, al decretar desde este lunes dos d\u00edas de duelo por los 122 muertos y miles de personas sin casa que han dejado hasta ahora los incendios forestales que ya figuran entre los tres m\u00e1s mort\u00edferos del mundo del siglo XXI.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-82355","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=82355"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82355\/revisions"}],"predecessor-version":[{"id":82357,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82355\/revisions\/82357"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=82355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=82355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=82355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}