{"id":82161,"date":"2024-01-30T16:24:35","date_gmt":"2024-01-30T22:24:35","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=82161"},"modified":"2024-01-30T16:24:35","modified_gmt":"2024-01-30T22:24:35","slug":"condenado-a-64-anos-de-carcel-en-san-miguel","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/condenado-a-64-anos-de-carcel-en-san-miguel\/","title":{"rendered":"Condenado a 64 a\u00f1os de c\u00e1rcel en San Miguel"},"content":{"rendered":"\n<p>Hamilton Barcenas<\/p>\n\n\n\n<p>Luego de una exhaustiva investigaci\u00f3n, un supuesto corredor de la Mara Salvatrucha (MS-13) que operaba en San Miguel, fue condenado a 64 a\u00f1os de prisi\u00f3n por los delitos de homicidio agravado y agrupaciones il\u00edcitas.<\/p>\n\n\n\n<p>Inicialmente, las investigaciones de la Fiscal\u00eda General de la Rep\u00fablica (FGR), revelaron que el sujeto identificado como Marlon Ariel Mel\u00e9ndez Maldonado, priv\u00f3 de libertar a una persona en marzo de 2014 y luego la asesin\u00f3. Por este caso, el Ministerio P\u00fablico logr\u00f3 que se le impusiera la pena m\u00e1xima en los tribunales.<\/p>\n\n\n\n<p>En el segundo caso, se determin\u00f3 que Marlon Maldonado ten\u00eda el cargo de corredor de la clica Chilanguera Locos Salvatruchos, que operaba en el municipio de Chirilagua, San Miguel; adem\u00e1s de Jucuar\u00e1n en Usulut\u00e1n. La sentencia fue impuesta por el Tribunal Segundo Contra el Crimen Organizado B de San Miguel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de una exhaustiva investigaci\u00f3n, un supuesto corredor de la Mara Salvatrucha (MS-13) que operaba en San Miguel, fue condenado a 64 a\u00f1os de prisi\u00f3n.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[4698,609,5257,7080],"class_list":["post-82161","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias","tag-condena","tag-judiciales","tag-san-miguel","tag-tribunales"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=82161"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82161\/revisions"}],"predecessor-version":[{"id":82164,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82161\/revisions\/82164"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=82161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=82161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=82161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}