{"id":82146,"date":"2024-01-30T12:20:10","date_gmt":"2024-01-30T18:20:10","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=82146"},"modified":"2024-01-30T12:20:17","modified_gmt":"2024-01-30T18:20:17","slug":"medicos-solicitan-libertad-de-asociacion","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/medicos-solicitan-libertad-de-asociacion\/","title":{"rendered":"M\u00e9dicos solicitan libertad de asociaci\u00f3n"},"content":{"rendered":"\n<p><em><strong>Brenda V\u00e1squez<\/strong><\/em><\/p>\n\n\n\n<p>Representantes de la Federaci\u00f3n de Profesionales de la Medicina fueron invitados a la Comisi\u00f3n Pol\u00edtica de la Asamblea Legislativa para estudiar la Ley de Especialidades de las Profesiones M\u00e9dicas.<\/p>\n\n\n\n<p>La Federaci\u00f3n solicita que cualquier asociaci\u00f3n pueda denominarse colegio y propone la creaci\u00f3n de un ente que certifique y recertifique las especialidades m\u00e9dicas, garantizando atenci\u00f3n de calidad y \u00e9tica, seg\u00fan su representante, Carlos Brizuela. <\/p>\n\n\n\n<p>\u201cHemos venido a solicitar adem\u00e1s la garant\u00eda de libertad de asociaci\u00f3n, es decir, que no sea obligatorio pertenecer al Colegio M\u00e9dico para poder unirse a una asociaci\u00f3n de especialistas. Adem\u00e1s, que toda asociaci\u00f3n pueda llamarse colegio, ya que actualmente ninguna puede llamarse as\u00ed\u201d, representante de FEDEMED, Carlos Brizuela.<\/p>\n\n\n\n<p>El presidente del \u00f3rgano legislativo, Ernesto Castro, afirm\u00f3 que continuar\u00e1n el estudio de cada punto solicitado. <\/p>\n\n\n\n<p>Para la pr\u00f3xima sesi\u00f3n, acordaron invitar al Ministro de Salud Francisco Alab\u00ed, la Directora del Instituto Salvadore\u00f1o del Seguro Social M\u00f3nica Ayala, representantes del Consejo Superior de Salud P\u00fablica y de la Junta de Vigilancia de la Profesi\u00f3n M\u00e9dica, programada para el 12 de febrero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brenda V\u00e1squez Representantes de la Federaci\u00f3n de Profesionales de la Medicina fueron invitados a la Comisi\u00f3n Pol\u00edtica de la Asamblea Legislativa para estudiar la Ley&hellip; <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-82146","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=82146"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82146\/revisions"}],"predecessor-version":[{"id":82157,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/82146\/revisions\/82157"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=82146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=82146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=82146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}