{"id":81518,"date":"2024-01-12T09:34:36","date_gmt":"2024-01-12T15:34:36","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=81518"},"modified":"2024-01-12T09:34:36","modified_gmt":"2024-01-12T15:34:36","slug":"arevalo-a-punto-de-asumir-la-presidencia-de-guatemala-pese-a-arremetida-judicial","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/arevalo-a-punto-de-asumir-la-presidencia-de-guatemala-pese-a-arremetida-judicial\/","title":{"rendered":"Ar\u00e9valo a punto de asumir la presidencia de Guatemala pese a arremetida judicial"},"content":{"rendered":"\n<p>AFP<\/p>\n\n\n\n<p>El socialdem\u00f3crata Bernardo Ar\u00e9valo debe asumir el domingo la presidencia de Guatemala tras enfrentar una incesante arremetida judicial que atribuy\u00f3 a su promesa de rescatar la fr\u00e1gil democracia guatemalteca de la \u00e9lite corrupta que seg\u00fan \u00e9l se aferra al poder.<\/p>\n\n\n\n<p>Este exdiplom\u00e1tico y soci\u00f3logo de 65 a\u00f1os, que denunci\u00f3 esa ofensiva como un intento de &#8220;golpe de Estado&#8221;, ser\u00e1 juramentado en el Teatro Nacional Miguel \u00c1ngel Asturias, en sesi\u00f3n solemne de un Congreso que le ser\u00e1 adverso.<\/p>\n\n\n\n<p>Desde que pas\u00f3 en junio al balotaje contra todo pron\u00f3stico, sorte\u00f3 los intentos de la Fiscal\u00eda por levantar su inmunidad y anular el resultado electoral, pero deber\u00e1 encarar la suspensi\u00f3n de su partido Semilla y el riesgo de que sus diputados tengan poco margen de maniobra.<\/p>\n\n\n\n<p>Respaldado por Estados Unidos, la Uni\u00f3n Europea, pa\u00edses latinoamericanos y organismos internacionales, Ar\u00e9valo relevar\u00e1 al derechista Alejandro Giammattei, a quien sus seguidores acusan de aupar a la fiscal general Consuelo Porras, punta de lanza de la embestida judicial.<\/p>\n\n\n\n<p>La tarea le ser\u00e1 inmensa. &#8220;Gobernar\u00e1 coexistiendo con la fiscal que&#8221; lo &#8220;ha atacado&#8221; y &#8220;afectado la democracia a niveles inimaginables&#8221;, afirm\u00f3 a la AFP Edie Cux, director de Acci\u00f3n Ciudadana, versi\u00f3n local de Transparencia Internacional.<\/p>\n\n\n\n<p>Ar\u00e9valo despert\u00f3 enormes expectativas en una sociedad hastiada de la corrupci\u00f3n, azotada por la violencia de las pandillas y del narcotr\u00e1fico, y donde seis de cada diez guatemaltecos vive en pobreza.<\/p>\n\n\n\n<p>&#8220;Indudablemente es una enorme responsabilidad. Pero la gente sabe que no es una tarea que se resuelve de la noche a la ma\u00f1ana&#8221;, coment\u00f3 Ar\u00e9valo en entrevista con AFP&nbsp;a fines de diciembre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; &#8220;Reconstruir la democracia&#8221; &#8211;<\/h2>\n\n\n\n<p>Hijo del primer presidente democr\u00e1tico de Guatemala, Juan Jos\u00e9 Ar\u00e9valo (1945-1951), gestor de reformas sociales, el futuro gobernante prometi\u00f3 cerrar el grifo de dinero p\u00fablico que ha enriquecido a las \u00e9lites, mientras la poblaci\u00f3n pasa penurias.<\/p>\n\n\n\n<p>Uno de cada dos ni\u00f1os menores de cinco a\u00f1os sufre desnutrici\u00f3n, y el analfabetismo es del 18%. La mayor econom\u00eda de Centroam\u00e9rica expulsa cada a\u00f1o a decenas de miles en busca de trabajo en Estados Unidos, cuyas remesas ayudan a sostener el pa\u00eds (20% del PIB), seg\u00fan datos oficiales.<\/p>\n\n\n\n<p>Pero para avanzar en lo social, seg\u00fan Ar\u00e9valo, debe comenzar la &#8220;lucha sostenida y gradual&#8221; por rescatar instituciones que dice fueron &#8220;cooptadas&#8221; por las &#8220;\u00e9lites corruptas&#8221;, como la Fiscal\u00eda, el Congreso, los tribunales o la Contralor\u00eda. &nbsp;<\/p>\n\n\n\n<p>&#8220;Es un problema sist\u00e9mico&#8221;, sostiene.<\/p>\n\n\n\n<p>Su estrategia incluye la creaci\u00f3n de una comisi\u00f3n que proponga reformas para frenar el enriquecimiento il\u00edcito y el clientelismo pol\u00edtico en una Guatemala que ocupa el puesto 30 en el ranking de corrupci\u00f3n de Transparencia Internacional, de 180 pa\u00edses.<\/p>\n\n\n\n<p>&#8220;Le toca una tarea important\u00edsima e impostergable de reconstruir la democracia&#8221; y lograr la gobernabilidad, coment\u00f3 a la AFP el exprocurador de Derechos Humanos, Jord\u00e1n Rodas, exiliado en Washington.<\/p>\n\n\n\n<p>Su experiencia en resoluci\u00f3n de conflictos, dice Rodas, puede ayudar. Ar\u00e9valo tambi\u00e9n es fil\u00f3sofo, estudi\u00f3 en Israel y Pa\u00edses Bajos y habla cinco idiomas.<\/p>\n\n\n\n<p>Naci\u00f3 en Montevideo y vivi\u00f3 de ni\u00f1o en Venezuela, M\u00e9xico y Chile, en el exilio de su padre tras el golpe de Estado orquestado por Washington contra el progresista Jacobo \u00c1rbenz (1951-1954).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Un presidente &#8220;emboscado&#8221; &#8211;<\/h2>\n\n\n\n<p>Durante meses se temi\u00f3 que los embates de la Fiscal\u00eda, que incluso allan\u00f3 sedes del tribunal electoral y decomis\u00f3 papeletas de votaci\u00f3n, impidiera que Ar\u00e9valo tomara el poder.<\/p>\n\n\n\n<p>En el camino quedaron varios detenidos y exiliados, un pila de acciones legales a favor y en contra de Ar\u00e9valo, y una bater\u00eda de sanciones de Washington contra fiscales, jueces, funcionarios y unos 100 diputados a quienes se\u00f1al\u00f3 de corrupci\u00f3n y de socavar la democracia.<\/p>\n\n\n\n<p>La Corte de Constitucionalidad debi\u00f3 exigir garant\u00edas para el traspaso de mando, e incluso el jueves otorg\u00f3 un &#8220;amparo&#8221; a la vicepresidenta electa, Karin Herrera, ante rumores de una orden de captura.<\/p>\n\n\n\n<p>Ar\u00e9valo afirma que de las primeras cosas que har\u00e1 como presidente ser\u00e1 pedir la renuncia de Porras. Pero los analistas advierten que la ofensiva en su contra est\u00e1 lejos de acabar.<\/p>\n\n\n\n<p>&#8220;Van a tener al presidente emboscado, al primer descuido querr\u00e1n levantar su inmunidad y destituirlo&#8221;, afirm\u00f3 a AFP Manfrendo Marroqu\u00edn, cofundador de Acci\u00f3n Ciudadana.<\/p>\n\n\n\n<p>En su ruta a la investidura, Ar\u00e9valo tuvo el apoyo decisivo de los j\u00f3venes, muy activos en redes sociales, y los ind\u00edgenas, hist\u00f3ricamente marginados y quienes son el 40% de los 17,8 millones de guatemaltecos.<\/p>\n\n\n\n<p>Durmiendo a la intemperie, grupos de ind\u00edgenas se mantuvieron m\u00e1s de 100 d\u00edas frente a la Fiscal\u00eda para exigir la renuncia de Porras.<\/p>\n\n\n\n<p>&#8220;Tendr\u00e1 que responder a sus expectativas. Pero no se puede pretender que venga con una varita m\u00e1gica&#8221;, afirm\u00f3 Rodas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP El socialdem\u00f3crata Bernardo Ar\u00e9valo debe asumir el domingo la presidencia de Guatemala tras enfrentar una incesante arremetida judicial que atribuy\u00f3 a su promesa de&hellip; <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[7014,667],"class_list":["post-81518","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias","tag-bernardo-arevalo","tag-guatemala"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/81518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=81518"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/81518\/revisions"}],"predecessor-version":[{"id":81520,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/81518\/revisions\/81520"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=81518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=81518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=81518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}