{"id":80597,"date":"2023-12-13T11:57:20","date_gmt":"2023-12-13T17:57:20","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=80597"},"modified":"2023-12-13T11:57:20","modified_gmt":"2023-12-13T17:57:20","slug":"conoce-el-horario-para-ver-la-mejor-lluvia-de-estrellas-del-2023-en-el-salvador","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/conoce-el-horario-para-ver-la-mejor-lluvia-de-estrellas-del-2023-en-el-salvador\/","title":{"rendered":"Conoce el horario para ver la mejor lluvia de estrellas del 2023 en El Salvador"},"content":{"rendered":"\n<p>A partir de hoy, los salvadore\u00f1os tendr\u00e1n la oportunidad de presenciar una de las mejores lluvias de estrellas del a\u00f1o, las Geminidas. Este fen\u00f3meno astron\u00f3mico podr\u00e1 ser observado desde las 10:00 pm hasta la madrugada, ofreciendo un espect\u00e1culo natural que no requiere ning\u00fan instrumento \u00f3ptico, solo un lugar oscuro y la disposici\u00f3n de recostarse en el suelo.<\/p>\n\n\n\n<p>Las Geminidas alcanzar\u00e1n su punto m\u00e1ximo de visibilidad los d\u00edas 13 y 14 de diciembre, lo que significa que estos dos d\u00edas son ideales para disfrutar al m\u00e1ximo de este fen\u00f3meno astron\u00f3mico. A pesar de su nombre, las Geminidas no solo pueden ser vistas desde la constelaci\u00f3n G\u00e9minis, sino que iluminar\u00e1n todo el cielo nocturno.<\/p>\n\n\n\n<p>Para aquellos que se preguntan hacia d\u00f3nde dirigir su mirada para apreciar esta lluvia de estrellas, aunque aparentan provenir de la constelaci\u00f3n G\u00e9minis, ser\u00e1n visibles en todas las \u00e1reas del cielo nocturno. Un peque\u00f1o mapa de la ubicaci\u00f3n de la constelaci\u00f3n G\u00e9minis puede proporcionar una gu\u00eda visual \u00fatil.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Hacia adonde ver en el cielo la lluvia de estrellas  Geminidas? <br>Aparentan provenir de la constelaci\u00f3n G\u00e9minis pero se ver\u00e1n en todo el cielo nocturno; ac\u00e1 dejamos un peque\u00f1o mapa de la ubicaci\u00f3n de la constelaci\u00f3n G\u00e9minis: <a href=\"https:\/\/t.co\/XfAbeq0RvD\">pic.twitter.com\/XfAbeq0RvD<\/a><\/p>&mdash; Asociaci\u00f3n Salvadore\u00f1a de Astronom\u00eda ( ASTRO ) (@ASTRO_SAL) <a href=\"https:\/\/twitter.com\/ASTRO_SAL\/status\/1734745320481829069?ref_src=twsrc%5Etfw\">December 13, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Este fen\u00f3meno astron\u00f3mico se origina cuando la Tierra atraviesa una corriente de fragmentos del asteroide 3200 Faet\u00f3n. La gravedad atrae estos fragmentos, que al ingresar a la atm\u00f3sfera se calcinan, generando destellos luminosos conocidos como estrellas fugaces.<\/p>\n\n\n\n<p>As\u00ed que, si eres amante de la astronom\u00eda o simplemente buscas disfrutar de un espect\u00e1culo natural \u00fanico, no te pierdas la oportunidad de maravillarte con las Geminidas en las noches del 13 y 14 de diciembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de hoy, los salvadore\u00f1os tendr\u00e1n la oportunidad de presenciar una de las mejores lluvias de estrellas del a\u00f1o, las Geminidas. Este fen\u00f3meno astron\u00f3mico&hellip; <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,28],"tags":[],"class_list":["post-80597","post","type-post","status-publish","format-standard","hentry","category-destacados","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=80597"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80597\/revisions"}],"predecessor-version":[{"id":80599,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80597\/revisions\/80599"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=80597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=80597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=80597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}