{"id":80279,"date":"2023-12-04T15:26:31","date_gmt":"2023-12-04T21:26:31","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=80279"},"modified":"2023-12-04T15:26:57","modified_gmt":"2023-12-04T21:26:57","slug":"enfrentan-juicio-17-miembros-del-barrio-18-por-actos-delictivos-en-usulutan","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/enfrentan-juicio-17-miembros-del-barrio-18-por-actos-delictivos-en-usulutan\/","title":{"rendered":"Enfrentan Juicio 17 Miembros del Barrio 18 por Actos Delictivos en Usulut\u00e1n"},"content":{"rendered":"\n<p>Hoy comenz\u00f3 el juicio contra 17 presuntos pandilleros pertenecientes al Barrio 18, quienes enfrentan cargos por diversos delitos cometidos entre los a\u00f1os 2019 y 2020 en el sector de la Bah\u00eda de Jiquilisco y Puerto El Triunfo en Usulut\u00e1n.<\/p>\n\n\n\n<p>Uno de los casos m\u00e1s alarmantes que ser\u00e1 examinado durante el juicio involucra un episodio en el cual estos individuos, seg\u00fan la acusaci\u00f3n, amenazaron con armas de fuego a un grupo de pescadores. Durante el violento encuentro, los acusados perpetraron el robo de dos motores y una lancha, elementos que, seg\u00fan las investigaciones, fueron posteriormente utilizados para el traslado de armas de fuego.<\/p>\n\n\n\n<p>Los delitos que se les imputan a los pandilleros son variados y de gravedad. Entre ellos se encuentran cuatro casos de extorsi\u00f3n agravada, un caso de robo agravado y la participaci\u00f3n en organizaciones terroristas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/megavision.com.sv\/web\/wp-content\/uploads\/2023\/12\/GAiFH2mXsAAbF-P-1024x554.jpeg\" alt=\"\" class=\"wp-image-80282\"\/><\/figure>\n\n\n\n<p>Las autoridades han recopilado pruebas contundentes que vinculan a los acusados con actividades il\u00edcitas, destacando la utilizaci\u00f3n de la lancha robada para el transporte de armas de fuego, lo que acent\u00faa la peligrosidad de la banda.<\/p>\n\n\n\n<p>El proceso judicial se lleva a cabo de manera virtual desde las c\u00e1rceles, dada la naturaleza violenta y la peligrosidad asociada a los miembros de estas pandillas. La Fiscal\u00eda ha presentado a testigos clave y evidencia documental para respaldar los cargos, buscando asegurar que la justicia prevalezca en este caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy comenz\u00f3 el juicio contra 17 presuntos pandilleros pertenecientes al Barrio 18, quienes enfrentan cargos por diversos delitos cometidos entre los a\u00f1os 2019 y 2020.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[2034,609,5191,6636,3610],"class_list":["post-80279","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias","tag-fgr","tag-judiciales","tag-pandilleros","tag-pnc","tag-usulutan"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=80279"}],"version-history":[{"count":2,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80279\/revisions"}],"predecessor-version":[{"id":80283,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80279\/revisions\/80283"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=80279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=80279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=80279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}