{"id":80233,"date":"2023-12-01T14:49:39","date_gmt":"2023-12-01T20:49:39","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=80233"},"modified":"2023-12-01T14:50:14","modified_gmt":"2023-12-01T20:50:14","slug":"agentes-encuentran-serpientes-en-varias-viviendas","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/agentes-encuentran-serpientes-en-varias-viviendas\/","title":{"rendered":"Agentes encuentran serpientes en varias viviendas"},"content":{"rendered":"\n<p>Alex Jim\u00e9nez<\/p>\n\n\n\n<p>La Divisi\u00f3n de Medio Ambiente de la Polic\u00eda Nacional Civil (PNC) llev\u00f3 a cabo varios rescates que culminaron con la liberaci\u00f3n de diversos animales silvestres en sus h\u00e1bitats naturales.<\/p>\n\n\n\n<p>En San Salvador, se rescataron y liberaron dos mapaches, una Boa constrictora conocida como &#8220;mazacuata&#8221;, un tacuaz\u00edn y una ardilla, proporcion\u00e1ndoles una oportunidad de regresar a su entorno natural para mantener su bienestar.<\/p>\n\n\n\n<p>Adem\u00e1s, en zonas como San Marcos y Sonsonate, se encontraron y liberaron serpientes de considerables dimensiones. En Apopa, se rescat\u00f3 y liber\u00f3 a un topo, mientras que en Ayutuxtepeque se liber\u00f3 un zorrillo.<\/p>\n\n\n\n<p>En otros sectores del pa\u00eds, se efectuaron rescates similares: en Nejapa se rescat\u00f3 y liber\u00f3 una Aurora, en La Libertad una Iguana Verde y en Santa Ana un Garrobo. Estos esfuerzos por parte de la Divisi\u00f3n de Medio Ambiente de la PNC demuestran un compromiso continuo con la preservaci\u00f3n de la fauna silvestre y su regreso a su h\u00e1bitat natural.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">La protecci\u00f3n de la fauna es importante para nosotros, por ello, a trav\u00e9s de la Divisi\u00f3n de Medio Ambiente velamos por el cuidado y la protecci\u00f3n de animales.<br><br>En diferentes zonas del pa\u00eds, realizamos rescates y posterior liberaci\u00f3n en su h\u00e1bitat de las especies:<br><br>\ud83d\udccdSan Salvador\u2026 <a href=\"https:\/\/t.co\/2pOyGDrIra\">pic.twitter.com\/2pOyGDrIra<\/a><\/p>&mdash; PNC El Salvador (@PNCSV) <a href=\"https:\/\/twitter.com\/PNCSV\/status\/1730662126560202886?ref_src=twsrc%5Etfw\">December 1, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Divisi\u00f3n de Medio Ambiente de la Polic\u00eda Nacional Civil (PNC) llev\u00f3 a cabo varios rescates que culminaron con la liberaci\u00f3n de diversos animales silvestres en sus h\u00e1bitats naturales.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-80233","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=80233"}],"version-history":[{"count":2,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80233\/revisions"}],"predecessor-version":[{"id":80237,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/80233\/revisions\/80237"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=80233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=80233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=80233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}