{"id":79334,"date":"2023-11-10T11:17:03","date_gmt":"2023-11-10T17:17:03","guid":{"rendered":"https:\/\/megavision.com.sv\/web\/?p=79334"},"modified":"2023-11-10T11:25:25","modified_gmt":"2023-11-10T17:25:25","slug":"abogados-cuestionan-abstencion-de-magistrado-julio-olivo","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/abogados-cuestionan-abstencion-de-magistrado-julio-olivo\/","title":{"rendered":"Abogados cuestionan abstenci\u00f3n de magistrado Julio Olivo"},"content":{"rendered":"\n<p><em><strong>Estefany Henr\u00edquez<\/strong><\/em><\/p>\n\n\n\n<p>La reciente inscripci\u00f3n del presidente Nayib Bukele para las pr\u00f3ximas elecciones contin\u00faa generando diversas reacciones. En el programa Pulso Ciudadano, expertos en derecho ofrecieron sus valoraciones sobre la resoluci\u00f3n del tribunal, aportando an\u00e1lisis y perspectivas al respecto.<\/p>\n\n\n\n<p>Los requisitos y las inhabilidades constitucionales y legales son aspectos cruciales que el Tribunal Supremo Electoral eval\u00faa al recibir una solicitud de inscripci\u00f3n presidencial. Seg\u00fan el abogado y experto electoral Juan Contreras, estos elementos fueron cumplidos por la f\u00f3rmula presentada por Nuevas Ideas, en su opini\u00f3n.<\/p>\n\n\n\n<p>En este contexto, abogados compartieron sus valoraciones sobre la resoluci\u00f3n del ente colegiado respecto a la inscripci\u00f3n de Bukele. Se profundiz\u00f3 en cuestiones legales y normativas relacionadas con el proceso electoral.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/PulsoCiudadano?src=hash&amp;ref_src=twsrc%5Etfw\">#PulsoCiudadano<\/a>\ud83d\udde3\ufe0f| \u201cMe encantar\u00eda preguntarle al magistrado Julio Olivo \u00bfpor qu\u00e9 no vot\u00f3 en contra? \u00c9l dijo el otro d\u00eda, votar\u00e9 conforme a la Constituci\u00f3n, pero no s\u00e9 a qu\u00e9 Constituci\u00f3n se refer\u00eda\u201d: abogado y comunicador, <a href=\"https:\/\/twitter.com\/MaoMaravilla?ref_src=twsrc%5Etfw\">@MaoMaravilla<\/a>. <a href=\"https:\/\/t.co\/rsUwXs1UAc\">pic.twitter.com\/rsUwXs1UAc<\/a><\/p>&mdash; Pulso Ciudadano (@PulsoCiudadanos) <a href=\"https:\/\/twitter.com\/PulsoCiudadanos\/status\/1722812806280413479?ref_src=twsrc%5Etfw\">November 10, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Un tema que no pas\u00f3 desapercibido fue la abstenci\u00f3n del magistrado Julio Olivo durante la inscripci\u00f3n del mandatario Nayib Bukele. Esta abstenci\u00f3n capt\u00f3 la atenci\u00f3n de los observadores y gener\u00f3 comentarios y especulaciones en el \u00e1mbito pol\u00edtico y jur\u00eddico.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/PulsoCiudadano?src=hash&amp;ref_src=twsrc%5Etfw\">#PulsoCiudadano<\/a> | \u201cEl c\u00f3digo electoral no regula esta figura de la abstenci\u00f3n\u201d, menciona el abogado y experto electoral, <a href=\"https:\/\/twitter.com\/ContrerasCC22?ref_src=twsrc%5Etfw\">@ContrerasCC22<\/a>. <a href=\"https:\/\/t.co\/yBR2hwHKD4\">pic.twitter.com\/yBR2hwHKD4<\/a><\/p>&mdash; Pulso Ciudadano (@PulsoCiudadanos) <a href=\"https:\/\/twitter.com\/PulsoCiudadanos\/status\/1722813922284130532?ref_src=twsrc%5Etfw\">November 10, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Al analizar el panorama pol\u00edtico actual del pa\u00eds, Maravilla puntualiz\u00f3 que podr\u00edan surgir reformas a la Constituci\u00f3n de la Rep\u00fablica en el futuro. Esta perspectiva abre la puerta a discusiones sobre posibles cambios en el marco legal, destacando la importancia de seguir de cerca los acontecimientos pol\u00edticos y jur\u00eddicos en el pa\u00eds. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entrevista completa:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#PulsoCiudadano\ud83d\udc4d\ud83d\udc4e\u00a1Buenas noches! Jueves 9 de noviembre. Sinton\u00edzanos por Canal 21.\" width=\"790\" height=\"444\" src=\"https:\/\/www.youtube.com\/embed\/qlmW2OgRpCQ?start=25&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La reciente inscripci\u00f3n del presidente Nayib Bukele para las pr\u00f3ximas elecciones contin\u00faa generando diversas reacciones. En el programa Pulso Ciudadano, expertos en derecho ofrecieron sus valoraciones sobre la resoluci\u00f3n del tribunal, aportando an\u00e1lisis y perspectivas al respecto.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,27],"tags":[556,740,108],"class_list":["post-79334","post","type-post","status-publish","format-standard","hentry","category-destacados","category-entrevista","tag-entrevista","tag-politica","tag-pulso-ciudadano"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/79334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=79334"}],"version-history":[{"count":3,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/79334\/revisions"}],"predecessor-version":[{"id":79338,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/79334\/revisions\/79338"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=79334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=79334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=79334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}