{"id":78363,"date":"2023-10-06T10:08:32","date_gmt":"2023-10-06T16:08:32","guid":{"rendered":"https:\/\/megavision.com.sv\/?p=78363"},"modified":"2023-10-06T10:08:33","modified_gmt":"2023-10-06T16:08:33","slug":"anda-adquiere-flota-de-vehiculos-para-agilizar-la-atencion-de-reportes","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/anda-adquiere-flota-de-vehiculos-para-agilizar-la-atencion-de-reportes\/","title":{"rendered":"ANDA adquiere flota de veh\u00edculos  para agilizar la atenci\u00f3n de reportes"},"content":{"rendered":"\n<p>Bajo el fin de dotar de herramientas t\u00e9cnicas y agilizar la capacidad de respuesta a los reportes ciudadanos, la Administraci\u00f3n Nacional de Acueductos y Alcantarillados (ANDA) hizo entrega de 41 veh\u00edculos.<\/p>\n\n\n\n<p>La flota vehicular se compone de 21 camiones livianos, 8 pick-ups doble cabina y 12 motocicletas. Estos fueron asignados a diferentes \u00e1reas del pa\u00eds. Once camiones livianos y seis pick-ups brindar\u00e1n servicios en la regi\u00f3n metropolitana, tres camiones en oriente, dos camiones y dos pick-ups en la zona central. Las doce motocicletas estar\u00e1n a disposici\u00f3n del \u00e1rea comercial y ser\u00e1n distribuidas a nivel nacional.<\/p>\n\n\n\n<p>El precio total de la inversi\u00f3n asciende a 650 mil d\u00f3lares, con una distribuci\u00f3n correspondiente de $630 mil entre los 21 camiones livianos y 8 pick-ups, mientras que las 12 motocicletas cuentan con un valor de 20 mil d\u00f3lares.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Esta ma\u00f1ana ANDA entreg\u00f3 una nueva flota vehicular conformada por 21 camiones , 8 pick ups doble cabina y 12 motocicletas para agilizar los reportes de atenci\u00f3n que a diario hace la ciudadan\u00eda .<br><br> <a href=\"https:\/\/twitter.com\/hashtag\/LaNoticiaATodaHora?src=hash&amp;ref_src=twsrc%5Etfw\">#LaNoticiaATodaHora<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TelenoticiasGMV?src=hash&amp;ref_src=twsrc%5Etfw\">#TelenoticiasGMV<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TelenoticiasMegavisi%C3%B3n?src=hash&amp;ref_src=twsrc%5Etfw\">#TelenoticiasMegavisi\u00f3n<\/a> <a href=\"https:\/\/t.co\/0uZO5qrro8\">pic.twitter.com\/0uZO5qrro8<\/a><\/p>&mdash; Telenoticias Megavisi\u00f3n (@TelenoticiasGMV) <a href=\"https:\/\/twitter.com\/TelenoticiasGMV\/status\/1710281040684585174?ref_src=twsrc%5Etfw\">October 6, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Rub\u00e9n Alem\u00e1n, Presidente de ANDA, mencion\u00f3 que estas adquisiciones servir\u00e1n &#8220;para atender los reportes de los usuarios en un tiempo corto y de manera efectiva, tambi\u00e9n va a permitir agilizar y canalizar cada uno de los casos que se reciben por medio de los canales de comunicaci\u00f3n, as\u00ed como tambi\u00e9n nos permitir\u00e1 ir a todos esos lugares que lo requieran\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, el Presidente de ANDA inform\u00f3 sobre el plazo de inscripci\u00f3n al proceso de saneamiento financiero con la instituci\u00f3n: &#8220;tienen hasta el 31 de diciembre para unirse al decreto, hoy en d\u00eda m\u00e1s de 15 mil personas lo han hecho. El proceso para registrarse consta de 3 pasos: acercarse a una agencia, llevar el DUI, NIT y copia de una factura y ya ah\u00ed cancelar el 10% de su cuota total, el resto se le puede dividir en 12 cuotas o en casos excepcionales en 24%\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el fin de dotar de herramientas t\u00e9cnicas y agilizar la capacidad de respuesta a los reportes ciudadanos, la Administraci\u00f3n Nacional de Acueductos y Alcantarillados (ANDA) hizo entrega de 41 veh\u00edculos.\u00a0<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[1877],"class_list":["post-78363","post","type-post","status-publish","format-standard","hentry","category-destacados","category-noticias","tag-anda"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/78363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=78363"}],"version-history":[{"count":2,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/78363\/revisions"}],"predecessor-version":[{"id":78367,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/78363\/revisions\/78367"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=78363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=78363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=78363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}