{"id":70511,"date":"2023-05-09T15:45:17","date_gmt":"2023-05-09T21:45:17","guid":{"rendered":"https:\/\/megavision.com.sv\/?p=70511"},"modified":"2023-05-09T15:45:18","modified_gmt":"2023-05-09T21:45:18","slug":"nintendo-supero-objetivos-anuales-pero-se-muestra-prudente-para-el-futuro","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/nintendo-supero-objetivos-anuales-pero-se-muestra-prudente-para-el-futuro\/","title":{"rendered":"Nintendo super\u00f3 objetivos anuales, pero se muestra prudente para el futuro"},"content":{"rendered":"\n<p><em>AFP<\/em><\/p>\n\n\n\n<p>Nintendo, pionero japon\u00e9s de los videojuegos, anunci\u00f3 este martes que sus resultados anuales fueron superiores a sus previsiones gracias a las ventas, pero se mostr\u00f3 prudente para el futuro por la ca\u00edda de las de su consola Switch.<\/p>\n\n\n\n<p>Durante el conjunto de su ejercicio 2022\/23, que termin\u00f3 a finales de marzo, Nintendo obtuvo un beneficio neto de 432,800 millones de yenes [3,200 millones de d\u00f3lares] y limit\u00f3 el descenso del beneficio neto al 9% con respecto al ejercicio fiscal anterior.<\/p>\n\n\n\n<p>Su facturaci\u00f3n anual (1,6 billones de yenes), en descenso m\u00e1s moderado (-5,5%), se apoy\u00f3 en particular en sus ventas de videojuegos.<\/p>\n\n\n\n<p>&#8220;Pok\u00e9mon Escarlata&#8221; y &#8220;P\u00farpura&#8221;, &#8220;Splatoon 3&#8221; o &#8220;Nintendo Switch Sports&#8221;, pero tambi\u00e9n t\u00edtulos m\u00e1s antiguos como &#8220;Mario Kart 8 Deluxe&#8221;, fueron los que m\u00e1s \u00e9xito registraron.<\/p>\n\n\n\n<p>Sin embargo, la empresa con sede en Kioto (oeste) vio sus ventas de consolas Switch caer un 22%, a 18 millones de unidades.<\/p>\n\n\n\n<p>La compa\u00f1\u00eda justific\u00f3 ese descenso por la penuria de los semiconductores y por unas ventas menos din\u00e1micas de lo previsto durante las fiestas de fin de a\u00f1o.<\/p>\n\n\n\n<p>Para 2023\/24, el grupo anunci\u00f3 previsiones muy prudentes y espera un beneficio neto de 340,000 millones de yenes, lo que implicar\u00eda una ca\u00edda interanual de 21%.<\/p>\n\n\n\n<p>En cuanto a la facturaci\u00f3n, la compa\u00f1\u00eda prev\u00e9 alcanzar un volumen de negocio de 1,450 billones de yenes, contando en particular con el lanzamiento el viernes del esperado &#8220;The Legend of Zelda: Tears of the Kingdom&#8221;.<\/p>\n\n\n\n<p>Para 2023\/24, Nintendo prev\u00e9 una nueva ca\u00edda significativa (-16,5%) de sus ventas de Switch, su consula lanzada hace siete a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP Nintendo, pionero japon\u00e9s de los videojuegos, anunci\u00f3 este martes que sus resultados anuales fueron superiores a sus previsiones gracias a las ventas, pero se&hellip; <\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,28,29],"tags":[6422,3234,6421],"class_list":["post-70511","post","type-post","status-publish","format-standard","hentry","category-el-sotano","category-entretenimiento","category-juveniles","tag-consola-switch","tag-nintendo","tag-pionero-japones-de-los-videojuegos"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/70511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=70511"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/70511\/revisions"}],"predecessor-version":[{"id":70515,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/70511\/revisions\/70515"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=70511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=70511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=70511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}