{"id":55280,"date":"2022-09-28T12:07:12","date_gmt":"2022-09-28T18:07:12","guid":{"rendered":"https:\/\/megavision.com.sv\/?p=55280"},"modified":"2022-09-28T12:14:31","modified_gmt":"2022-09-28T18:14:31","slug":"ocho-estadios-albergaran-los-partidos-del-mundial-de-catar%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/megavision.com.sv\/web\/ocho-estadios-albergaran-los-partidos-del-mundial-de-catar%ef%bf%bc\/","title":{"rendered":"Ocho estadios albergar\u00e1n los partidos del Mundial de Catar\ufffc"},"content":{"rendered":"\n<p><em>AFP<\/em><\/p>\n\n\n\n<p>Los partidos del Mundial de Catar (20 de noviembre al 18 de diciembre) se repartir\u00e1n en ocho estadios, de los que s\u00f3lo uno exist\u00eda cuando el peque\u00f1o emirato fue elegido como sede de la Copa del Mundo.<\/p>\n\n\n\n<p>Estos son los estadios que albergar\u00e1n el mayor evento futbol\u00edstico del planeta:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Lusail Iconic Stadium de Lusail (80,000 plazas)<\/h2>\n\n\n\n<p>El mayor de los estadios construidos acoger\u00e1 la final de la competici\u00f3n, el 18 de diciembre, adem\u00e1s de otros partidos. Est\u00e1 situado en Lusail, una ciudad especialmente creada para el evento. Fue oficialmente inaugurado a principios de septiembre, durante la Lusail Super Cup entre los equipos campeones de Arabia Saudita y Egipto, Al Hilal y Zamalek.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Khalifa International Stadium de Doha (45.416 plazas)<\/h2>\n\n\n\n<p>Construido en 1976, es el \u00fanico estadio que exist\u00eda antes de la designaci\u00f3n en 2010 del pa\u00eds como anfitri\u00f3n del Mundial. El recinto fue renovado en 2017 y sus dos nuevos arcos lo hacen mucho m\u00e1s moderno. Ya ha albergado numerosas competiciones, como los Juegos Asi\u00e1ticos, cinco partidos de la Copa del Mundo de Clubes (2019), entre ellos la final entre Liverpool y Flamengo, y la Copa de Asia de la AFC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Al Bayt Stadium de Al Khor (60,000 plazas)<\/h2>\n\n\n\n<p>Este estadio de dif\u00edcil acceso para los aficionados (solamente mediante autocar o taxi) fue construido en la costa del nordeste del pa\u00eds, a 35 km de la capital, siguiendo la forma de las tiendas de los beduinos. En este recinto debutar\u00e1 la selecci\u00f3n anfitriona contra Ecuador el 20 de noviembre a las 16h00 GMT en el partido inaugural del torneo y tambi\u00e9n albergar\u00e1 uno de los partidos m\u00e1s atractivos de la primera fase, el Espa\u00f1a-Alemania.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Al Janoub Stadium de Al-Wakrah (40,000 plazas)<\/h2>\n\n\n\n<p>Las formas de este estadio est\u00e1n inspiradas en los cascos de los barcos de pesca de perlas, durante mucho tiempo presentes en las costas de la Pen\u00ednsula Ar\u00e1biga. El recinto fue inaugurado con la victoria del Al Duhail contra Al-Sadd en la final de la Copa del Emir en 2019.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Education City Stadium de Doha (40,000 plazas)<\/h2>\n\n\n\n<p>De muy f\u00e1cil acceso por metro y situado en medio de campus universitarios, su silueta tiene la forma de un diamante. La capacidad del recinto se reducir\u00e1 a la mitad tras el evento mundialista, algo que ocurrir\u00e1 tambi\u00e9n con otros estadios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Ahmad Bin Ali Stadium de Al Rayyan (60,000 plazas)<\/h2>\n\n\n\n<p>Una l\u00ednea de metro se ha creado especialmente para unir Doha con este estadio situado en una de las ciudades m\u00e1s hist\u00f3ricas del pa\u00eds, no lejos del desierto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Al Thumama Stadium de Doha (40,000 plazas)<\/h2>\n\n\n\n<p>Su dise\u00f1o se inspira en la &#8216;taqiyah&#8217;, el tocado tradicional de los hombres de la regi\u00f3n. La competici\u00f3n comenzar\u00e1 en este recinto con un Senegal-Holanda el lunes 21 de noviembre (10h00 GMT). Tras la competici\u00f3n, el estadio pasar\u00e1 de 40,000 a 20,000 plazas y deber\u00eda albergar tambi\u00e9n una cl\u00ednica del deporte y un hotel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; 974 Stadium de Doha (40,000 plazas)<\/h2>\n\n\n\n<p>Este recinto ha sido fabricado a partir de contenedores y otros materiales reutilizados. Ser\u00e1 totalmente desmantelado despu\u00e9s del torneo. El n\u00famero 974 corresponde al prefijo telef\u00f3nico internacional de Catar, pero tambi\u00e9n al n\u00famero de contenedores usados en la construcci\u00f3n del estadio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFP Los partidos del Mundial de Catar (20 de noviembre al 18 de diciembre) se repartir\u00e1n en ocho estadios, de los que s\u00f3lo uno exist\u00eda&hellip; <\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[1183,769],"class_list":["post-55280","post","type-post","status-publish","format-standard","hentry","category-deportes","tag-estadios","tag-mundial-de-catar"],"_links":{"self":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/55280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/comments?post=55280"}],"version-history":[{"count":1,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/55280\/revisions"}],"predecessor-version":[{"id":55281,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/posts\/55280\/revisions\/55281"}],"wp:attachment":[{"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/media?parent=55280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/categories?post=55280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megavision.com.sv\/web\/wp-json\/wp\/v2\/tags?post=55280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}